{"id":52255,"date":"2025-07-10T07:00:00","date_gmt":"2025-07-10T06:00:00","guid":{"rendered":"https:\/\/algarve7.pt\/?p=52255"},"modified":"2025-07-09T18:58:46","modified_gmt":"2025-07-09T17:58:46","slug":"aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo","status":"publish","type":"post","link":"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/","title":{"rendered":"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">No passado dia 7 de julho, assinalou-se o 37.\u00ba Anivers\u00e1rio do Parque Natural do Sudoeste Alentejano e Costa Vicentina (PNSACV) este ano celebrado no munic\u00edpio de Vila do Bispo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Foi um dia de partilha, entre representantes e t\u00e9cnicos das entidades associadas ao PNSACV e ao seu Plano de Cogest\u00e3o, com um programa que se iniciou com uma rece\u00e7\u00e3o de boas-vindas no\u00a0Museu de Vila do Bispo &#8211; Celeiro da Hist\u00f3ria\u00a0pela presidente da C\u00e2mara Municipal, Rute Silva. Seguiu-se uma palestra proferida pelo Professor Doutor Rui Dias, ge\u00f3logo da Universidade de \u00c9vora e do Centro Ci\u00eancia Viva Estremoz, sobre o patrim\u00f3nio geol\u00f3gico e paleontol\u00f3gico do PNSACV, e a apresenta\u00e7\u00e3o do projeto municipal &#8220;As Aves dos Pastores&#8221; (https:\/\/avesdospastores.org), pelo ornit\u00f3logo Simon Wates. O programa prosseguiu com uma visita guiada ao Museu de Vila do Bispo e um p\u00e9riplo interpretativo que passou pelo Cabo de S\u00e3o Vicente, pelo Menir do Padr\u00e3o, na Raposeira, e pela reserva patrimonial da Boca do Rio, em Budens, sob orienta\u00e7\u00e3o da equipa t\u00e9cnica do Museu de Vila do Bispo.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud835\udc02\ud835\udc2e\ud835\udc2b\ud835\udc22\ud835\udc28\ud835\udc2c\ud835\udc22\ud835\udc1d\ud835\udc1a\ud835\udc1d\ud835\udc1e\ud835\udc2c&nbsp;\ud835\udc2c\ud835\udc28\ud835\udc1b\ud835\udc2b\ud835\udc1e&nbsp;\ud835\udc28&nbsp;\ud835\udc0f\ud835\udc0d\ud835\udc12\ud835\udc00\ud835\udc02\ud835\udc15:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A 7 de julho de 1988 foi formalmente definida a \u00e1rea protegida do PNSACV, pelo Decreto-Lei n.\u00ba 241\/88 (https:\/\/files.diariodarepublica.pt\/&#8230;\/07\/15500\/27812792.pdf), a base legal para a cria\u00e7\u00e3o do nosso Parque Natural, institu\u00eddo, sete anos depois, no dia 21 de setembro de 1995, pelo Decreto Regulamentar n.\u00ba 26\/95 (https:\/\/diariodarepublica.pt\/&#8230;\/decreto&#8230;\/1995-916945603).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estendendo-se pela costa sudoeste de Portugal, entre S\u00e3o Torpes, a sul de Sines, e Burgau, j\u00e1 na costa sul algarvia, numa faixa mar\u00edtima de 2 km de largura, o PNSACV abrange territ\u00f3rios nos concelhos de Sines, Odemira, Aljezur e Vila do Bispo, ocupando uma superf\u00edcie total de 89.568,77 ha (60.577,25 ha de \u00e1rea terrestre e 28.991,52ha de zona marinha).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reserva um riqu\u00edssimo, diversificado e particularmente significativo conjunto de valores patrimoniais, naturais e culturais, designadamente paisag\u00edsticos, flor\u00edsticos, faun\u00edsticos, geol\u00f3gicos, paleontol\u00f3gicos, arqueol\u00f3gicos, hist\u00f3ricos e etnol\u00f3gicos, que importa preservar, investigar, dar a conhecer, valorizar de forma sustent\u00e1vel e transmitir \u00e0s futuras gera\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No passado dia 7 de julho, assinalou-se o 37.\u00ba Anivers\u00e1rio do Parque Natural do Sudoeste Alentejano e Costa Vicentina (PNSACV)<\/p>\n","protected":false},"author":1,"featured_media":52256,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[36,62,84],"class_list":["post-52255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade","tag-algarve","tag-atualidade","tag-vila-do-bispo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo - Algarve 7<\/title>\n<meta name=\"description\" content=\"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo Atualidade\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo - Algarve 7\" \/>\n<meta property=\"og:description\" content=\"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo Atualidade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/\" \/>\n<meta property=\"og:site_name\" content=\"Algarve 7\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/algarve7\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/algarve7\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-10T06:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/algarve7.pt\/wp-content\/uploads\/2025\/07\/1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Algarve 7\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Algarvesete\" \/>\n<meta name=\"twitter:site\" content=\"@Algarvesete\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Algarve 7\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/algarve7.pt\\\/index.php\\\/2025\\\/07\\\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\\\/atualidade\\\/07\\\/00\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/algarve7.pt\\\/index.php\\\/2025\\\/07\\\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\\\/atualidade\\\/07\\\/00\\\/\"},\"author\":{\"name\":\"Algarve 7\",\"@id\":\"https:\\\/\\\/algarve7.pt\\\/#\\\/schema\\\/person\\\/23fa70681308e7b319a3204bcea45e0c\"},\"headline\":\"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo\",\"datePublished\":\"2025-07-10T06:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/algarve7.pt\\\/index.php\\\/2025\\\/07\\\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\\\/atualidade\\\/07\\\/00\\\/\"},\"wordCount\":368,\"publisher\":{\"@id\":\"https:\\\/\\\/algarve7.pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/algarve7.pt\\\/index.php\\\/2025\\\/07\\\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\\\/atualidade\\\/07\\\/00\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/algarve7.pt\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/1.jpg\",\"keywords\":[\"Algarve\",\"Atualidade\",\"Vila do Bispo\"],\"articleSection\":[\"Atualidade\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/algarve7.pt\\\/index.php\\\/2025\\\/07\\\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\\\/atualidade\\\/07\\\/00\\\/\",\"url\":\"https:\\\/\\\/algarve7.pt\\\/index.php\\\/2025\\\/07\\\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\\\/atualidade\\\/07\\\/00\\\/\",\"name\":\"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo - Algarve 7\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/algarve7.pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/algarve7.pt\\\/index.php\\\/2025\\\/07\\\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\\\/atualidade\\\/07\\\/00\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/algarve7.pt\\\/index.php\\\/2025\\\/07\\\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\\\/atualidade\\\/07\\\/00\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/algarve7.pt\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/1.jpg\",\"datePublished\":\"2025-07-10T06:00:00+00:00\",\"description\":\"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo Atualidade\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/algarve7.pt\\\/index.php\\\/2025\\\/07\\\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\\\/atualidade\\\/07\\\/00\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/algarve7.pt\\\/index.php\\\/2025\\\/07\\\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\\\/atualidade\\\/07\\\/00\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/algarve7.pt\\\/index.php\\\/2025\\\/07\\\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\\\/atualidade\\\/07\\\/00\\\/#primaryimage\",\"url\":\"https:\\\/\\\/algarve7.pt\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/1.jpg\",\"contentUrl\":\"https:\\\/\\\/algarve7.pt\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/1.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/algarve7.pt\\\/index.php\\\/2025\\\/07\\\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\\\/atualidade\\\/07\\\/00\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/algarve7.pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/algarve7.pt\\\/#website\",\"url\":\"https:\\\/\\\/algarve7.pt\\\/\",\"name\":\"Algarve 7\",\"description\":\"Informa\u00e7\u00e3o sobre o Algarve\",\"publisher\":{\"@id\":\"https:\\\/\\\/algarve7.pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/algarve7.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/algarve7.pt\\\/#organization\",\"name\":\"Algarve 7\",\"url\":\"https:\\\/\\\/algarve7.pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/algarve7.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/algarve7.pt\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Logo-8.jpg\",\"contentUrl\":\"https:\\\/\\\/algarve7.pt\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Logo-8.jpg\",\"width\":1680,\"height\":1186,\"caption\":\"Algarve 7\"},\"image\":{\"@id\":\"https:\\\/\\\/algarve7.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/algarve7\",\"https:\\\/\\\/x.com\\\/Algarvesete\",\"https:\\\/\\\/www.instagram.com\\\/jornalalgarve7\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/algarve7\",\"https:\\\/\\\/www.pinterest.pt\\\/geral0939\\\/_created\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/algarve7.pt\\\/#\\\/schema\\\/person\\\/23fa70681308e7b319a3204bcea45e0c\",\"name\":\"Algarve 7\",\"sameAs\":[\"https:\\\/\\\/algarve7.pt\",\"https:\\\/\\\/www.facebook.com\\\/algarve7\"],\"url\":\"https:\\\/\\\/algarve7.pt\\\/index.php\\\/author\\\/geralalgarve7-pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo - Algarve 7","description":"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo Atualidade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/","og_locale":"pt_PT","og_type":"article","og_title":"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo - Algarve 7","og_description":"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo Atualidade","og_url":"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/","og_site_name":"Algarve 7","article_publisher":"https:\/\/www.facebook.com\/algarve7","article_author":"https:\/\/www.facebook.com\/algarve7","article_published_time":"2025-07-10T06:00:00+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/algarve7.pt\/wp-content\/uploads\/2025\/07\/1.jpg","type":"image\/jpeg"}],"author":"Algarve 7","twitter_card":"summary_large_image","twitter_creator":"@Algarvesete","twitter_site":"@Algarvesete","twitter_misc":{"Escrito por":"Algarve 7","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/#article","isPartOf":{"@id":"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/"},"author":{"name":"Algarve 7","@id":"https:\/\/algarve7.pt\/#\/schema\/person\/23fa70681308e7b319a3204bcea45e0c"},"headline":"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo","datePublished":"2025-07-10T06:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/"},"wordCount":368,"publisher":{"@id":"https:\/\/algarve7.pt\/#organization"},"image":{"@id":"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/#primaryimage"},"thumbnailUrl":"https:\/\/algarve7.pt\/wp-content\/uploads\/2025\/07\/1.jpg","keywords":["Algarve","Atualidade","Vila do Bispo"],"articleSection":["Atualidade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/","url":"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/","name":"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo - Algarve 7","isPartOf":{"@id":"https:\/\/algarve7.pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/#primaryimage"},"image":{"@id":"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/#primaryimage"},"thumbnailUrl":"https:\/\/algarve7.pt\/wp-content\/uploads\/2025\/07\/1.jpg","datePublished":"2025-07-10T06:00:00+00:00","description":"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo Atualidade","breadcrumb":{"@id":"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/#primaryimage","url":"https:\/\/algarve7.pt\/wp-content\/uploads\/2025\/07\/1.jpg","contentUrl":"https:\/\/algarve7.pt\/wp-content\/uploads\/2025\/07\/1.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/algarve7.pt\/index.php\/2025\/07\/aniversario-do-pnsacv-celebrado-no-municipio-de-vila-do-bispo\/atualidade\/07\/00\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/algarve7.pt\/"},{"@type":"ListItem","position":2,"name":"Anivers\u00e1rio do PNSACV celebrado no munic\u00edpio de Vila do Bispo"}]},{"@type":"WebSite","@id":"https:\/\/algarve7.pt\/#website","url":"https:\/\/algarve7.pt\/","name":"Algarve 7","description":"Informa\u00e7\u00e3o sobre o Algarve","publisher":{"@id":"https:\/\/algarve7.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/algarve7.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/algarve7.pt\/#organization","name":"Algarve 7","url":"https:\/\/algarve7.pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/algarve7.pt\/#\/schema\/logo\/image\/","url":"https:\/\/algarve7.pt\/wp-content\/uploads\/2020\/10\/Logo-8.jpg","contentUrl":"https:\/\/algarve7.pt\/wp-content\/uploads\/2020\/10\/Logo-8.jpg","width":1680,"height":1186,"caption":"Algarve 7"},"image":{"@id":"https:\/\/algarve7.pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/algarve7","https:\/\/x.com\/Algarvesete","https:\/\/www.instagram.com\/jornalalgarve7\/","https:\/\/www.linkedin.com\/company\/algarve7","https:\/\/www.pinterest.pt\/geral0939\/_created\/"]},{"@type":"Person","@id":"https:\/\/algarve7.pt\/#\/schema\/person\/23fa70681308e7b319a3204bcea45e0c","name":"Algarve 7","sameAs":["https:\/\/algarve7.pt","https:\/\/www.facebook.com\/algarve7"],"url":"https:\/\/algarve7.pt\/index.php\/author\/geralalgarve7-pt\/"}]}},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/pcezmW-dAP","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/algarve7.pt\/wp-content\/uploads\/2025\/07\/1.jpg","_links":{"self":[{"href":"https:\/\/algarve7.pt\/index.php\/wp-json\/wp\/v2\/posts\/52255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/algarve7.pt\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/algarve7.pt\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/algarve7.pt\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/algarve7.pt\/index.php\/wp-json\/wp\/v2\/comments?post=52255"}],"version-history":[{"count":0,"href":"https:\/\/algarve7.pt\/index.php\/wp-json\/wp\/v2\/posts\/52255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/algarve7.pt\/index.php\/wp-json\/wp\/v2\/media\/52256"}],"wp:attachment":[{"href":"https:\/\/algarve7.pt\/index.php\/wp-json\/wp\/v2\/media?parent=52255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/algarve7.pt\/index.php\/wp-json\/wp\/v2\/categories?post=52255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/algarve7.pt\/index.php\/wp-json\/wp\/v2\/tags?post=52255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}